{"id":3721,"date":"2024-07-01T07:57:46","date_gmt":"2024-07-01T07:57:46","guid":{"rendered":"https:\/\/mimaforklift.com\/?post_type=portfolio&#038;p=3721"},"modified":"2026-08-21T07:10:07","modified_gmt":"2026-08-21T07:10:07","slug":"narrorw-body-multi-directional-forklift-mq25","status":"publish","type":"portfolio","link":"https:\/\/www.mimaforklift.com\/es\/electric-order-picker\/mha10\/","title":{"rendered":"Recogepedidos el\u00e9ctrico de nivel medio Serie MHA 1,0 toneladas Cabina abierta\/cerrada"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3721\" class=\"elementor elementor-3721\" data-elementor-post-type=\"portfolio\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c9b826c elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c9b826c\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6830166\" data-id=\"6830166\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90d8436 elementor-widget elementor-widget-shortcode\" data-id=\"90d8436\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><nav  aria-label=\"miga de pan\"><ol class=\"breadcrumb\" itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li class=\"breadcrumb-item active\" aria-current=\"page\" itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Inicio<\/span><meta itemprop=\"position\" content=\"1\"><\/li><\/ol><\/nav><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed757d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed757d3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-439e1de\" data-id=\"439e1de\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80e7a30 elementor-skin-slideshow elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"80e7a30\" data-element_type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;slideshow&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/09\/4-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/09\/5-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/09\/3-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"recogepedidos el\u00e9ctrico MHA10\" style=\"background-image: url(&#039;https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/09\/1-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Siguiente<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-thumbnails-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/09\/4-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/09\/5-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/09\/3-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"recogepedidos el\u00e9ctrico MHA10\" style=\"background-image: url(&#039;https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/09\/1-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-67bc6dc\" data-id=\"67bc6dc\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af954a0 elementor-widget elementor-widget-heading\" data-id=\"af954a0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recogepedidos el\u00e9ctrico de nivel medio Serie MHA 1,0 toneladas Cabina abierta\/cerrada<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f89f66 elementor-widget elementor-widget-heading\" data-id=\"9f89f66\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">01 - Descripci\u00f3n del producto:<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8171144 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8171144\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-dot-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm80 248c0 44.112-35.888 80-80 80s-80-35.888-80-80 35.888-80 80-80 80 35.888 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Marca : MiMA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-dot-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm80 248c0 44.112-35.888 80-80 80s-80-35.888-80-80 35.888-80 80-80 80 35.888 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">N\u00ba de art\u00edculo : MHA10<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-dot-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm80 248c0 44.112-35.888 80-80 80s-80-35.888-80-80 35.888-80 80-80 80 35.888 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Capacidad: 1,0 toneladas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-dot-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm80 248c0 44.112-35.888 80-80 80s-80-35.888-80-80 35.888-80 80-80 80 35.888 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Altura de elevaci\u00f3n: 5760 mm<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-dot-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm80 248c0 44.112-35.888 80-80 80s-80-35.888-80-80 35.888-80 80-80 80 35.888 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tipo de alimentaci\u00f3n: Bater\u00eda interior<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aeb45e9 elementor-widget elementor-widget-text-editor\" data-id=\"aeb45e9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div><div>La altura m\u00e1xima de elevaci\u00f3n es de 6,4 metros, con una altura de recogida de hasta 7,6 metros y una capacidad de carga m\u00e1xima de 1 tonelada. Puede elevar la carga mientras se desplaza, lo que mejora la eficiencia operativa. El modo de conducci\u00f3n con el operador en la cabina ofrece una visi\u00f3n m\u00e1s clara.<\/div><div>\u00a0<\/div><div>Equipada con dispositivos de visualizaci\u00f3n de ruedas y cintur\u00f3n de seguridad, garantiza un funcionamiento m\u00e1s seguro y fiable. Su excelente dise\u00f1o ergon\u00f3mico la convierte en la opci\u00f3n ideal para operaciones de recogida en almac\u00e9n.<\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a87534c elementor-widget elementor-widget-heading\" data-id=\"a87534c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">02 - Aplicaciones:<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd1a1ed elementor-widget elementor-widget-text-editor\" data-id=\"cd1a1ed\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>Los preparadores de pedidos MHA se utilizan principalmente para operaciones de recogida de material de las estanter\u00edas de los almacenes.<\/li><li><div>Son adecuadas para recoger materiales de estanter\u00edas de nivel bajo a medio.<\/div><\/li><li><div>Para trabajos ligeros en interiores.<\/div><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b4230e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4230e5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e5387a0\" data-id=\"e5387a0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c58584d elementor-widget elementor-widget-button\" data-id=\"c58584d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2NCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicitar presupuesto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-522cc71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"522cc71\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-86b2293\" data-id=\"86b2293\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-50f288f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50f288f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9df9f79\" data-id=\"9df9f79\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ea1e2b elementor-widget elementor-widget-heading\" data-id=\"5ea1e2b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Descargas<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3285c4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e3285c4\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4daa102 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4daa102\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2025\/02\/MHA-MHA13-Order-Picker-202501.pdf\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-arrow-alt-circle-down\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200zm-32-316v116h-67c-10.7 0-16 12.9-8.5 20.5l99 99c4.7 4.7 12.3 4.7 17 0l99-99c7.6-7.6 2.2-20.5-8.5-20.5h-67V140c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Folleto MHA MHA13 Recogedor de pedidos - 202501<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5c44507\" data-id=\"5c44507\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67ee393 elementor-widget elementor-widget-heading\" data-id=\"67ee393\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">V\u00eddeos de operaciones<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d854701 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d854701\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b149ebd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b149ebd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65a1551\" data-id=\"65a1551\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a0e001 elementor-widget elementor-widget-heading\" data-id=\"6a0e001\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recogedora de pedidos el\u00e9ctrica: Lo que necesita saber <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9139bf3 e-grid e-con-full e-con e-parent\" data-id=\"9139bf3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-154a676 elementor-widget elementor-widget-image\" data-id=\"154a676\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"460\" src=\"https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/07\/MHA10-updated-web-iamge-3.webp\" class=\"attachment-large size-large wp-image-12671\" alt=\"\" srcset=\"https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/07\/MHA10-updated-web-iamge-3.webp 600w, https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/07\/MHA10-updated-web-iamge-3-300x230.webp 300w, https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/07\/MHA10-updated-web-iamge-3-16x12.webp 16w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dce0d79 elementor-widget elementor-widget-image\" data-id=\"dce0d79\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"460\" src=\"https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/07\/MHA10-updated-web-iamge-1-1.webp\" class=\"attachment-large size-large wp-image-12670\" alt=\"\" srcset=\"https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/07\/MHA10-updated-web-iamge-1-1.webp 600w, https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/07\/MHA10-updated-web-iamge-1-1-300x230.webp 300w, https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/07\/MHA10-updated-web-iamge-1-1-16x12.webp 16w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42784b2 elementor-widget elementor-widget-image\" data-id=\"42784b2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"460\" src=\"https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/07\/MHA10-updated-web-iamge-4.webp\" class=\"attachment-large size-large wp-image-12672\" alt=\"\" srcset=\"https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/07\/MHA10-updated-web-iamge-4.webp 600w, https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/07\/MHA10-updated-web-iamge-4-300x230.webp 300w, https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/07\/MHA10-updated-web-iamge-4-16x12.webp 16w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ef9657 elementor-widget elementor-widget-text-editor\" data-id=\"9ef9657\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div><div>La tapa abatible de la bater\u00eda permite un acceso r\u00e1pido y c\u00f3modo para el mantenimiento de la bater\u00eda.<\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-275c7d0 elementor-widget elementor-widget-text-editor\" data-id=\"275c7d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div><div>La palanca de control ergon\u00f3mica importada permite subir y bajar la carga de forma suave y proporcional.<\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3523cf0 elementor-widget elementor-widget-text-editor\" data-id=\"3523cf0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div><div>El interruptor de pulgar permite un control intuitivo con una sola mano para optimizar los procesos de preparaci\u00f3n de pedidos.<\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06bc593 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06bc593\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7fa0a0e\" data-id=\"7fa0a0e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-efceead elementor-widget elementor-widget-heading\" data-id=\"efceead\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recogedora de pedidos Detalles y especificaciones del producto<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a167a23 elementor-widget elementor-widget-ucaddon_mml_table\" data-id=\"a167a23\" data-element_type=\"widget\" data-widget_type=\"ucaddon_mml_table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start MML TABLE -->\n<style>\/* widget: MML TABLE *\/\n\n.mml-ue-table {\n\toverflow: auto;\n}\n\n.mml-ue-table table {\n\twidth: 100%;\n  \tmin-width: 600px;\n}\n\n.mml-ue-table table td{\n\tcolor: #010101;\n  \ttext-align: center;\n}\n.mml-ue-table table td:first-child{\n\tcolor: ;\n  \tbackground-color: ;\n}\n\n.mml-ue-table table td:nth-child(2n-1) {\n\tcolor: ;\n  \tbackground-color: ;\n}\n.mml-ue-table table td:nth-child(2n) {\n\tcolor: ;\n  \tbackground-color: ;\n}\n\n<\/style>\n\n<div class=\"mml-ue-table uc_mml_table_elementor_a167a23\">\n\t<table width=\"1391\"><tbody><tr><td width=\"254\">Fabricante<\/td><td width=\"93\">\u00a0<\/td><td width=\"270\">MIMA<\/td><td width=\"264\">MIMA<\/td><td width=\"235\">MIMA<\/td><td width=\"273\">MIMA<\/td><\/tr><tr><td>Modelo<\/td><td>\u00a0<\/td><td>MHA10 (cabina abierta)<\/td><td>MHA10 (cabina abierta)<\/td><td>MHA10 (cabina cerrada)<\/td><td>MHA10 (cabina cerrada)<\/td><\/tr><tr><td>C\u00f3digo de modelo<\/td><td>\u00a0<\/td><td>MHA10L (m\u00e1stil d\u00faplex) [1]\u00a0<\/td><td>MHA10S (m\u00e1stil tr\u00edptico) [1]<\/td><td>MHA10L (m\u00e1stil d\u00faplex) [1]\u00a0<\/td><td>MHA10S (m\u00e1stil tr\u00edptico) [1]<\/td><\/tr><tr><td>Tipo de potencia<\/td><td>\u00a0<\/td><td>El\u00e9ctrica<\/td><td>El\u00e9ctrica<\/td><td>El\u00e9ctrica<\/td><td>El\u00e9ctrica<\/td><\/tr><tr><td>Operaci\u00f3n<\/td><td>\u00a0<\/td><td>Preparaci\u00f3n de pedidos<\/td><td>Preparaci\u00f3n de pedidos<\/td><td>Preparaci\u00f3n de pedidos<\/td><td>Preparaci\u00f3n de pedidos<\/td><\/tr><tr><td>Capacidad de carga<\/td><td>Q(kg)<\/td><td>1000<\/td><td>1000<\/td><td>1000<\/td><td>1000<\/td><\/tr><tr><td>Distancia del centro de carga<\/td><td>C(mm)<\/td><td>500<\/td><td>500<\/td><td>500<\/td><td>500<\/td><\/tr><tr><td>Voladizo delantero<\/td><td>x(mm)<\/td><td>148<\/td><td>148<\/td><td>148<\/td><td>148<\/td><\/tr><tr><td>Distancia entre ejes<\/td><td>y(mm)<\/td><td>1410<\/td><td>1410<\/td><td>1410<\/td><td>1410<\/td><\/tr><tr><td>Peso en servicio (bater\u00eda incluida)<\/td><td>kg<\/td><td>2490<\/td><td>2830<\/td><td>2490<\/td><td>2830<\/td><\/tr><tr><td>Carga por eje, cargado delante\/detr\u00e1s<\/td><td>kg<\/td><td>940\/2550<\/td><td>1130\/2700<\/td><td>940\/2550<\/td><td>1130\/2700<\/td><\/tr><tr><td>Carga sobre el eje, en vac\u00edo delante\/detr\u00e1s<\/td><td>kg<\/td><td>1410\/1080<\/td><td>1610\/1220<\/td><td>1410\/1080<\/td><td>1610\/1220<\/td><\/tr><tr><td>Tipo de neum\u00e1tico, delantero\/trasero<\/td><td>\u00a0<\/td><td>Poliuretano<\/td><td>Poliuretano<\/td><td>Poliuretano<\/td><td>Poliuretano<\/td><\/tr><tr><td>Tama\u00f1o del neum\u00e1tico delantero<\/td><td>mm<\/td><td>\u03c6150 \u00d7 90<\/td><td>\u03c6150 \u00d7 90<\/td><td>\u03c6150 \u00d7 90<\/td><td>\u03c6150 \u00d7 90<\/td><\/tr><tr><td>Tama\u00f1o del neum\u00e1tico trasero<\/td><td>mm<\/td><td>\u03c6254 \u00d7 102<\/td><td>\u03c6254 \u00d7 102<\/td><td>\u03c6254 \u00d7 102<\/td><td>\u03c6254 \u00d7 102<\/td><\/tr><tr><td>N\u00famero de ruedas delanteras\/traseras (X=drive)<\/td><td>\u00a0<\/td><td>4\/1X<\/td><td>4\/1X<\/td><td>4\/1X<\/td><td>4\/1X<\/td><\/tr><tr><td>Ancho de v\u00eda trasero<\/td><td>b10(mm)<\/td><td>1008<\/td><td>1008<\/td><td>1008<\/td><td>1008<\/td><\/tr><tr><td>Ancho de v\u00eda delantero<\/td><td>b11(mm)<\/td><td>0<\/td><td>0<\/td><td>0<\/td><td>0<\/td><\/tr><tr><td>Altura de la protecci\u00f3n superior<\/td><td>h6(mm)<\/td><td>2270<\/td><td>2270<\/td><td>2270<\/td><td>2270<\/td><\/tr><tr><td>Distancia al suelo, altura m\u00ednima de la superficie de trabajo<\/td><td>h7(mm)<\/td><td>260<\/td><td>260<\/td><td>260<\/td><td>260<\/td><\/tr><tr><td>Altura de elevaci\u00f3n auxiliar<\/td><td>h9 (mm)<\/td><td>670<\/td><td>670<\/td><td>670<\/td><td>670<\/td><\/tr><tr><td>Distancia al suelo, superficie m\u00ednima de las horquillas<\/td><td>h13(mm)<\/td><td>70<\/td><td>70<\/td><td>70<\/td><td>70<\/td><\/tr><tr><td>Longitud total<\/td><td>l1(mm)<\/td><td>2825<\/td><td>2835<\/td><td>2825<\/td><td>2835<\/td><\/tr><tr><td>Longitud desde el cuerpo hasta la superficie de la horquilla<\/td><td>l2(mm)<\/td><td>1755<\/td><td>1765<\/td><td>1755<\/td><td>1765<\/td><\/tr><tr><td>Anchura total<\/td><td>b1\/b2(mm)<\/td><td>1150\/1150<\/td><td>1150\/1150<\/td><td>1150\/1150<\/td><td>1150\/1150<\/td><\/tr><tr><td>Dimensiones de la horquilla<\/td><td>l\/e\/s(mm)<\/td><td>1070\/100\/40<\/td><td>1070\/100\/40<\/td><td>1070\/100\/40<\/td><td>1070\/100\/40<\/td><\/tr><tr><td>Ancho del bastidor de las horquillas<\/td><td>b3(mm)<\/td><td>730<\/td><td>730<\/td><td>730<\/td><td>730<\/td><\/tr><tr><td width=\"254\">Horquilla exterior<\/td><td>b5(mm)<\/td><td>700\uff5e220<\/td><td>700\uff5e220<\/td><td>700\uff5e220<\/td><td>700\uff5e220<\/td><\/tr><tr><td width=\"254\">Anchura sobre rodillos gu\u00eda<\/td><td>b6(mm)<\/td><td>1336<\/td><td>1336<\/td><td>1336<\/td><td>1336<\/td><\/tr><tr><td>Distancia al suelo por debajo del m\u00e1stil\u00a0<\/td><td>m1(mm)<\/td><td>50<\/td><td>50<\/td><td>50<\/td><td>50<\/td><\/tr><tr><td>Distancia al suelo, carro<\/td><td>m2(mm)<\/td><td>50<\/td><td>50<\/td><td>50<\/td><td>50<\/td><\/tr><tr><td width=\"254\">Ancho del pasillo<\/td><td>Ast(mm)<\/td><td width=\"270\">1750[2]<\/td><td width=\"264\">1750[2]<\/td><td width=\"235\">1750[2]<\/td><td width=\"273\">1750[2]<\/td><\/tr><tr><td>Radio de giro<\/td><td>Wa(mm)<\/td><td>1625<\/td><td>1625<\/td><td>1625<\/td><td>1625<\/td><\/tr><tr><td>Anchura del pasillo principal<\/td><td>mm<\/td><td width=\"270\">\u2265(2920+400)[3]<\/td><td width=\"264\">\u2265(2930+400)[3]<\/td><td width=\"235\">\u2265(2920+400)[3]<\/td><td width=\"273\">\u2265(2930+400)[3]<\/td><\/tr><tr><td>Velocidad de desplazamiento, cargado\/descargado<\/td><td>km\/h<\/td><td>6\/6<\/td><td>6\/6<\/td><td>6\/6<\/td><td>6\/6<\/td><\/tr><tr><td>Velocidad de elevaci\u00f3n, cargado\/descargado<\/td><td>mm\/s<\/td><td>115\/140<\/td><td>115\/140<\/td><td>115\/140<\/td><td>115\/140<\/td><\/tr><tr><td>Velocidad de descenso, cargado\/descargado<\/td><td>mm\/s<\/td><td>125\/125<\/td><td>125\/125<\/td><td>125\/125<\/td><td>125\/125<\/td><\/tr><tr><td>Gradeabilidad, cargado\/descargado<\/td><td>un tercio de la ra\u00edz cuadrada de theta<\/td><td>\/<\/td><td>\/<\/td><td>\/<\/td><td>\/<\/td><\/tr><tr><td>Freno de marcha<\/td><td>\u00a0<\/td><td width=\"270\">Frenado regenerativo \/ frenado electromagn\u00e9tico<\/td><td width=\"264\">Frenado regenerativo \/ frenado electromagn\u00e9tico<\/td><td width=\"235\">Frenado regenerativo \/ frenado electromagn\u00e9tico<\/td><td width=\"273\">Frenado regenerativo \/ frenado electromagn\u00e9tico<\/td><\/tr><tr><td>Freno de servicio<\/td><td>\u00a0<\/td><td>Electromagn\u00e9tico<\/td><td>Electromagn\u00e9tico<\/td><td>Electromagn\u00e9tico<\/td><td>Electromagn\u00e9tico<\/td><\/tr><tr><td>Motor de accionamiento, potencia S2=60<\/td><td>kw<\/td><td>2,5 CA<\/td><td>2,5 CA<\/td><td>2,5 CA<\/td><td>2,5 CA<\/td><\/tr><tr><td>Motor de elevaci\u00f3n, potencia S3=15%<\/td><td>kw<\/td><td>3,2 CC<\/td><td>3,2 CC<\/td><td>3,2 CC<\/td><td>3,2 CC<\/td><\/tr><tr><td>Tensi\u00f3n\/capacidad nominal de la bater\u00eda\u00a0<\/td><td>(V)\/(Ah)<\/td><td>24\/400[4]<\/td><td>24\/400[4]<\/td><td>24\/400[4]<\/td><td>24\/400[4]<\/td><\/tr><tr><td>Peso de la bater\u00eda<\/td><td>kg<\/td><td>340<\/td><td>340<\/td><td>340<\/td><td>340<\/td><\/tr><tr><td>Tipo de control de la transmisi\u00f3n<\/td><td>\u00a0<\/td><td>CA<\/td><td>CA<\/td><td>CA<\/td><td>CA<\/td><\/tr><tr><td>Nivel de ruido en el o\u00eddo del operador (norma EN 12053)<\/td><td>\u00a0<\/td><td>70<\/td><td>70<\/td><td>70<\/td><td>70<\/td><\/tr><\/tbody><\/table>\n<\/div>\n<!-- end MML TABLE -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-824085f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"824085f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b7ce5f5\" data-id=\"b7ce5f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-390811a elementor-widget elementor-widget-heading\" data-id=\"390811a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u00e1s productos en MiMA<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-447376d elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-pp-posts\" data-id=\"447376d\" data-element_type=\"widget\" data-widget_type=\"pp-posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-posts-container\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t<div class=\"pp-posts pp-posts-skin-classic elementor-grid pp-posts-grid\" data-query-type=\"custom\" data-layout=\"grid\" data-page=\"3721\" data-skin=\"classic\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-post-wrap pp-grid-item-wrap elementor-grid-item post-12093 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolios-narrow-aisle-forklift\">\n\t\t\t\t\t\t<div class=\"pp-post pp-grid-item\">\n\t\t\t\t\t\t<div class=\"pp-post-thumbnail\">\n\t\t\t<a class=\"pp-post-thumbnail-wrap\" href=\"https:\/\/www.mimaforklift.com\/es\/narrow-aisle-forklift\/stand-on-3-way-pallet-stacker-mc12-mc16-2\/\" title=\"Apilador de pal\u00e9s de 3 direcciones con operador de pie, serie MC, 0,8 toneladas\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"644\" src=\"https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/08\/3-WAY-pallet-stacker-MC12-1.jpg\" class=\"attachment-large size-large wp-image-6515\" alt=\"Apilador de pal\u00e9s 3-WAY\" srcset=\"https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/08\/3-WAY-pallet-stacker-MC12-1.jpg 720w, https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/08\/3-WAY-pallet-stacker-MC12-1-300x268.jpg 300w, https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2024\/08\/3-WAY-pallet-stacker-MC12-1-600x537.jpg 600w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"pp-post-content-wrap\">\n\t\t\t\t\t<div class=\"pp-post-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-post-title\">\n\t\t\t\t<a href=\"https:\/\/www.mimaforklift.com\/es\/narrow-aisle-forklift\/stand-on-3-way-pallet-stacker-mc12-mc16-2\/\">Apilador de pal\u00e9s de 3 direcciones con operador de pie, serie MC, 0,8 toneladas<\/a>\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<a class=\"pp-posts-button elementor-button elementor-size-sm\" href=\"https:\/\/www.mimaforklift.com\/es\/narrow-aisle-forklift\/stand-on-3-way-pallet-stacker-mc12-mc16-2\/\" title=\"Apilador de pal\u00e9s de 3 direcciones con operador de pie, serie MC, 0,8 toneladas\" aria-label=\"M\u00e1s informaci\u00f3n sobre la apiladora de pal\u00e9s de 3 direcciones con operador de pie de la serie MC de 0,8 toneladas\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pp-button-text\">\n\t\t\t\t\tSeguir leyendo\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"pp-button-icon elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"pp-post-wrap pp-grid-item-wrap elementor-grid-item post-8845 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolios-narrow-aisle-forklift\">\n\t\t\t\t\t\t<div class=\"pp-post pp-grid-item\">\n\t\t\t\t\t\t<div class=\"pp-post-thumbnail\">\n\t\t\t<a class=\"pp-post-thumbnail-wrap\" href=\"https:\/\/www.mimaforklift.com\/es\/narrow-aisle-forklift\/3-way-pallet-stacker-mcc12\/\" title=\"Carretilla de torreta elevable Estanter\u00eda de doble profundidad MCC12 1,2 toneladas\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"644\" src=\"https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2025\/03\/MCC12-\u4e3b\u56fe.jpg\" class=\"attachment-large size-large wp-image-8810\" alt=\"MCC12 Cami\u00f3n con torreta elevadora\" srcset=\"https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2025\/03\/MCC12-\u4e3b\u56fe.jpg 720w, https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2025\/03\/MCC12-\u4e3b\u56fe-300x268.jpg 300w, https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2025\/03\/MCC12-\u4e3b\u56fe-13x12.jpg 13w, https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2025\/03\/MCC12-\u4e3b\u56fe-600x537.jpg 600w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"pp-post-content-wrap\">\n\t\t\t\t\t<div class=\"pp-post-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-post-title\">\n\t\t\t\t<a href=\"https:\/\/www.mimaforklift.com\/es\/narrow-aisle-forklift\/3-way-pallet-stacker-mcc12\/\">Carretilla de torreta elevable Estanter\u00eda de doble profundidad MCC12 1,2 toneladas<\/a>\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<a class=\"pp-posts-button elementor-button elementor-size-sm\" href=\"https:\/\/www.mimaforklift.com\/es\/narrow-aisle-forklift\/3-way-pallet-stacker-mcc12\/\" title=\"Carretilla de torreta elevable Estanter\u00eda de doble profundidad MCC12 1,2 toneladas\" aria-label=\"Leer m\u00e1s sobre Carretilla con torreta elevable Estanter\u00eda de doble profundidad MCC12 1,2 toneladas\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pp-button-text\">\n\t\t\t\t\tSeguir leyendo\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"pp-button-icon elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"pp-post-wrap pp-grid-item-wrap elementor-grid-item post-8415 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolios-articulated-forklift portfolios-narrow-aisle-forklift\">\n\t\t\t\t\t\t<div class=\"pp-post pp-grid-item\">\n\t\t\t\t\t\t<div class=\"pp-post-thumbnail\">\n\t\t\t<a class=\"pp-post-thumbnail-wrap\" href=\"https:\/\/www.mimaforklift.com\/es\/articulated-forklift\/mjd25\/\" title=\"Carretilla Elevadora Articulada Contrapesada Serie MJD 2.5ton\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"644\" src=\"https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2025\/01\/1.jpg\" class=\"attachment-large size-large wp-image-8628\" alt=\"1 Carretilla elevadora articulada MJD25\" srcset=\"https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2025\/01\/1.jpg 720w, https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2025\/01\/1-300x268.jpg 300w, https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2025\/01\/1-13x12.jpg 13w, https:\/\/www.mimaforklift.com\/wp-content\/uploads\/2025\/01\/1-600x537.jpg 600w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"pp-post-content-wrap\">\n\t\t\t\t\t<div class=\"pp-post-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-post-title\">\n\t\t\t\t<a href=\"https:\/\/www.mimaforklift.com\/es\/articulated-forklift\/mjd25\/\">Carretilla Elevadora Articulada Contrapesada Serie MJD 2.5ton<\/a>\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<a class=\"pp-posts-button elementor-button elementor-size-sm\" href=\"https:\/\/www.mimaforklift.com\/es\/articulated-forklift\/mjd25\/\" title=\"Carretilla Elevadora Articulada Contrapesada Serie MJD 2.5ton\" aria-label=\"Leer m\u00e1s sobre Carretilla elevadora articulada de contrapeso serie MJD de 2,5 toneladas\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pp-button-text\">\n\t\t\t\t\tSeguir leyendo\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"pp-button-icon elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f5e0205 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5e0205\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b3a70a7\" data-id=\"b3a70a7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"featured_media":6781,"parent":0,"menu_order":0,"template":"","portfolios":[34],"class_list":["post-3721","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolios-electric-order-picker"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mimaforklift.com\/es\/wp-json\/wp\/v2\/portfolio\/3721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mimaforklift.com\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.mimaforklift.com\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"version-history":[{"count":9,"href":"https:\/\/www.mimaforklift.com\/es\/wp-json\/wp\/v2\/portfolio\/3721\/revisions"}],"predecessor-version":[{"id":12675,"href":"https:\/\/www.mimaforklift.com\/es\/wp-json\/wp\/v2\/portfolio\/3721\/revisions\/12675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mimaforklift.com\/es\/wp-json\/wp\/v2\/media\/6781"}],"wp:attachment":[{"href":"https:\/\/www.mimaforklift.com\/es\/wp-json\/wp\/v2\/media?parent=3721"}],"wp:term":[{"taxonomy":"portfolios","embeddable":true,"href":"https:\/\/www.mimaforklift.com\/es\/wp-json\/wp\/v2\/portfolios?post=3721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}